{"id":39838,"date":"2025-10-28T09:19:50","date_gmt":"2025-10-28T13:19:50","guid":{"rendered":"https:\/\/expressaoms.com.br\/?p=39838"},"modified":"2025-10-28T09:19:50","modified_gmt":"2025-10-28T13:19:50","slug":"filha-de-gerson-palermo-maior-traficante-foragido-do-brasil-e-sequestrada-e-liberada-em-ms","status":"publish","type":"post","link":"https:\/\/expressaoms.com.br\/index.php\/2025\/10\/28\/filha-de-gerson-palermo-maior-traficante-foragido-do-brasil-e-sequestrada-e-liberada-em-ms\/","title":{"rendered":"Filha de Gerson Palermo, maior traficante foragido do Brasil, \u00e9 sequestrada e liberada em MS"},"content":{"rendered":"<p class=\"ds-markdown-paragraph\">A filha de Gerson Palermo, um dos maiores traficantes do Brasil e foragido desde 2020, foi sequestrada na noite de sexta-feira e libertada na madrugada de s\u00e1bado em Campo Grande. Apesar da pris\u00e3o de um suspeito e do relato da v\u00edtima que atribuiu a &#8220;culpa&#8221; do c\u00e1rcere privado ao pr\u00f3prio pai, as autoridades afirmam que ainda n\u00e3o t\u00eam certeza sobre as motiva\u00e7\u00f5es e o mandante do crime.<\/p>\n<p class=\"ds-markdown-paragraph\">A jovem de 25 anos contou \u00e0 pol\u00edcia que Palermo teria ligado para ela na sexta-feira afirmando que mandaria algu\u00e9m entregar uma quantia em dinheiro para ajudar nos custos do tratamento de sa\u00fade da av\u00f3, que est\u00e1 acamada. Quando essa pessoa chegou, ela entrou no ve\u00edculo e foi sequestrada. Segundo seu depoimento, os sequestradores cobravam a devolu\u00e7\u00e3o de um dinheiro ao pai, valor que ela alega n\u00e3o possuir.<\/p>\n<p class=\"ds-markdown-paragraph\">A defesa de Palermo apresentou uma vers\u00e3o diferente dos fatos. De acordo com o advogado do traficante, Amilton Ferreira, o pai teria deixado com a filha cerca de US$ 10 mil (aproximadamente R$ 53 mil), provenientes da venda de gado, para que ela guardasse o valor antes do sequestro. O advogado nega qualquer envolvimento de Palermo com o crime e afirma que &#8220;nunca um pai e uma m\u00e3e mandam sequestrar um filho, sempre acontece ao contr\u00e1rio&#8221;.<\/p>\n<h2 class=\"ds-markdown-paragraph\"><strong>Investiga\u00e7\u00e3o em andamento<\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\">O delegado Roberto Guimar\u00e3es, da Delegacia Especializada de Repress\u00e3o a Assaltos a Banco e Sequestros (Garras), mant\u00e9m cautela sobre o caso. &#8220;A v\u00edtima apresentou sua vers\u00e3o, de que teria sido sequestrada por uma quest\u00e3o de d\u00edvida, de dinheiro, de um foragido da Justi\u00e7a, o senhor Gerson Palermo. Se o senhor Gerson e a esposa dele t\u00eam envolvimento ou n\u00e3o, tudo isso ainda ser\u00e1 levantado&#8221;, afirmou.<\/p>\n<p class=\"ds-markdown-paragraph\">Um homem de 34 anos, identificado como Reinaldo Silva Farias &#8211; suposto propriet\u00e1rio do im\u00f3vel onde a jovem foi mantida ref\u00e9m -, foi preso em flagrante e teve a pris\u00e3o convertida em preventiva durante audi\u00eancia de cust\u00f3dia. A pol\u00edcia investiga a participa\u00e7\u00e3o de pelo menos mais duas pessoas no crime.<\/p>\n<p class=\"ds-markdown-paragraph\">Durante o per\u00edodo em que ficou em cativeiro no Bairro Moreninhas, os sequestradores enviaram fotos e mensagens de \u00e1udio da v\u00edtima para o marido dela, que acionou o Garras. Em seu depoimento, a jovem relatou ter sofrido viol\u00eancia f\u00edsica e psicol\u00f3gica, incluindo amea\u00e7as de mutila\u00e7\u00e3o, coronhadas, chutes e intimida\u00e7\u00f5es de morte. O companheiro da v\u00edtima tamb\u00e9m foi amea\u00e7ado caso n\u00e3o entregasse o dinheiro do resgate, que n\u00e3o chegou a ser pago.<\/p>\n<h2 class=\"ds-markdown-paragraph\"><strong>Quem \u00e9 Gerson Palermo<\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\">Com quase 70 anos, Gerson Palermo tem passagens pela pol\u00edcia desde o in\u00edcio da d\u00e9cada de 1990, principalmente por tr\u00e1fico de drogas. Conhecido como chef\u00e3o do Primeiro Comando da Capital (PCC) em Mato Grosso do Sul, ganhou notoriedade nacional em agosto de 2000 ao liderar o sequestro de um Boeing da Vasp com 67 pessoas a bordo. O avi\u00e3o foi desviado para Porecatu (PR), onde os criminosos levaram cerca de R$ 5,5 milh\u00f5es que estavam no compartimento de carga.<\/p>\n<p class=\"ds-markdown-paragraph\">Sua \u00faltima pris\u00e3o ocorreu em 2017 na Opera\u00e7\u00e3o All In, que desmantelou uma organiza\u00e7\u00e3o criminosa de tr\u00e1fico internacional de drogas e lavagem de dinheiro. Em agosto de 2019, foi condenado a 59 anos e nove meses de pris\u00e3o, mas oito meses depois conseguiu converter o regime para pris\u00e3o domiciliar atrav\u00e9s de habeas corpus concedido pelo desembargador Divoncir Schereiner Maran. Desde ent\u00e3o, Palermo permanece foragido da Justi\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A filha de Gerson Palermo, um dos maiores traficantes do Brasil e foragido desde 2020, foi sequestrada na noite de sexta-feira e libertada na madrugada de s\u00e1bado em Campo Grande. Apesar da pris\u00e3o de um suspeito e do relato da v\u00edtima que atribuiu a &#8220;culpa&#8221; do c\u00e1rcere privado ao pr\u00f3prio pai, as autoridades afirmam que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":39839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27,30,36,266,193],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39838"}],"collection":[{"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39838"}],"version-history":[{"count":1,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39838\/revisions"}],"predecessor-version":[{"id":39840,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39838\/revisions\/39840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/media\/39839"}],"wp:attachment":[{"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressaoms.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}